{"id":998,"count":21,"description":"","link":"https:\/\/www.privatepropertymallorca.com\/en\/category\/perfect-hideaways-on-mallorca\/","name":"Perfect Hideaways on Mallorca","slug":"perfect-hideaways-on-mallorca","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.privatepropertymallorca.com\/en\/wp-json\/wp\/v2\/categories\/998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.privatepropertymallorca.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.privatepropertymallorca.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.privatepropertymallorca.com\/en\/wp-json\/wp\/v2\/posts?categories=998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}