{"id":1074,"count":14,"description":"","link":"https:\/\/www.privatepropertymallorca.com\/es\/category\/perfect-hideaways-mallorca\/","name":"Perfect Hideaways Mallorca","slug":"perfect-hideaways-mallorca","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/categories\/1074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/posts?categories=1074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}