{"id":1147158,"date":"2024-08-12T11:05:05","date_gmt":"2024-08-12T09:05:05","guid":{"rendered":"https:\/\/www.privatepropertymallorca.com\/yoga-del-mar-spirit-festival-un-viaje-de-conexion-en-mallorca\/"},"modified":"2024-08-12T12:01:11","modified_gmt":"2024-08-12T10:01:11","slug":"yoga-del-mar-spirit-festival-un-viaje-de-conexion-en-mallorca","status":"publish","type":"post","link":"https:\/\/www.privatepropertymallorca.com\/es\/cultura-y-ocio\/yoga-del-mar-spirit-festival-un-viaje-de-conexion-en-mallorca\/","title":{"rendered":"Yoga del Mar Spirit Festival: Un viaje de conexi\u00f3n en Mallorca"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb559256&#8243; css=\u00bb\u00bb][\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_column_text css=\u00bb\u00bb]<strong>Yoga del Mar Spirit Festival: Un viaje de conexi\u00f3n en Mallorca<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mallorca: M\u00e1s que una simple isla de fiesta<\/strong><\/p>\n<p>Mallorca suele ser estereotipada como un destino de fiesta, pero la isla es una joya del Mediterr\u00e1neo que espera ser descubierta. Lejos de la animada vida nocturna, la isla ofrece una naturaleza deslumbrante, pueblos encantadores y una creciente comunidad de entusiastas del bienestar. Este entorno id\u00edlico ofrece el escenario perfecto para el Yoga del Mar Spirit Festival, un evento que promete una experiencia transformadora.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Una celebraci\u00f3n de mente, cuerpo y alma.<\/strong><\/p>\n<p>El Yoga del Mar Spirit Festival invita a los participantes a sumergirse en un mundo de yoga, meditaci\u00f3n y vida consciente. Centr\u00e1ndose en la conexi\u00f3n (con uno mismo, con los dem\u00e1s y con la naturaleza), el festival ofrece un programa diverso de actividades dise\u00f1adas para nutrir el alma. Desde din\u00e1micas sesiones de yoga hasta tranquilas pr\u00e1cticas de meditaci\u00f3n, hay algo para todos los gustos. La danza ext\u00e1tica, la m\u00fasica en vivo y los talleres inspiradores crean una atm\u00f3sfera animada, mientras que las charlas y ceremonias de sabidur\u00eda ofrecen una visi\u00f3n m\u00e1s profunda del crecimiento personal y el desarrollo espiritual.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Un sabor de Mallorca<\/strong><\/p>\n<p>El festival es m\u00e1s que un simple retiro; es una oportunidad para experimentar la verdadera esencia de Mallorca. Disfrute de comida deliciosa y saludable, explore los mercados locales y descubra los tesoros escondidos de la isla. La combinaci\u00f3n de paisajes impresionantes, aire fresco y una comunidad solidaria crea el ambiente perfecto para la relajaci\u00f3n, la renovaci\u00f3n y la inspiraci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Una alineaci\u00f3n de primera clase<\/strong><\/p>\n<p>El Yoga del Mar Spirit Festival impresiona con un cartel estelar de profesores y artistas de renombre, entre ellos Nessi Gomes, The Hanuman Project y Paco Colombas. Adem\u00e1s de estas estrellas internacionales, el festival tambi\u00e9n celebra el talento local y muestra la comunidad vibrante y diversa que Mallorca tiene para ofrecer.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Experimenta la magia<\/strong><\/p>\n<p>\u00danete al Yoga del Mar Spirit Festival y emb\u00e1rcate en un viaje de autodescubrimiento. Con\u00e9ctate con personas de ideas afines, explora tu yo interior y recon\u00e9ctate con la naturaleza. Insp\u00edrate con la belleza de Mallorca mientras luchas por una vida de equilibrio, armon\u00eda y prop\u00f3sito.<\/p>\n<p>\u00bfEst\u00e1s listo para vivir la magia de Mallorca? \u00bfPodemos ayudarle a encontrar las <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/busqueda-inmobiliaria\/\">propiedades en Mallorca<\/a>?<\/p>\n<p>&nbsp;<\/p>\n<p>Lea m\u00e1s sobre Yoga del Mar Spirit Festival aqu\u00ed:<\/p>\n<p>https:\/\/yogadelmar.es\/el-festival-del-esp\u00edritu.html<\/p>\n<p>&nbsp;<\/p>\n<p>&#8230;y enriquece tus experiencias espirituales con <a href=\"https:\/\/aromapura.com\/\">aromapura<\/a>:<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb1132312&#8243; onclick=\u00bbcustom_link\u00bb css=\u00bb\u00bb link=\u00bbhttps:\/\/www.privatepropertymallorca.com\/es\/cultura-y-ocio\/aromas-naturales-para-su-propiedad-en-mallorca-el-arte-del-diseno-de-interiores-con-aceites-esenciales-y-su-influencia-positiva-en-el-bienestar\/\u00bb][\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_column_text css=\u00bb\u00bb]<br \/>\n<a href=\"https:\/\/www.privatepropertymallorca.com\/es\/cultura-y-ocio\/aromas-naturales-para-su-propiedad-en-mallorca-el-arte-del-diseno-de-interiores-con-aceites-esenciales-y-su-influencia-positiva-en-el-bienestar\/\"><strong>Aromas naturales para su propiedad en Mallorca: el arte del dise\u00f1o de interiores con aceites esenciales y su influencia positiva en el bienestar.<\/strong><\/a><\/p>\n<p>Bienvenido a un concepto olfativo innovador para el sector inmobiliario que apela a los sentidos de sus potenciales compradores, inquilinos o residentes y crea una atm\u00f3sfera inolvidable.<\/p>\n<p><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/cultura-y-ocio\/aromas-naturales-para-su-propiedad-en-mallorca-el-arte-del-diseno-de-interiores-con-aceites-esenciales-y-su-influencia-positiva-en-el-bienestar\/\">leer m\u00e1s&#8230;<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column]<div id=\"ultimate-heading-9006a03db7e2e9ec\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-9006a03db7e2e9ec uvc-4483 \" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-9006a03db7e2e9ec h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"font-weight:normal;\">INMOBILIARIA SANTA PONSA<\/h2><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div id=\"wpestate_sh_anime_789\" class=\"article_container wpestate_anime wpestate_latest_listings_sh bottom-estate_property \"  data-type=\"estate_property\" data-category_ids=\"\" data-action_ids=\"\" data-city_ids=\"\" data-area_ids=\"\" data-state_ids=\"\" data-status_ids=\"\" data-number=\"40\" data-row-number=\"4\" data-align=\"vertical\" data-show_featured_only=\"no\"  data-random_pick=\"yes\"  data-featured_first=\"no\" data-page=\"1\" >  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1256519\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/preciosa-finca-con-vistas-al-mar-en-camp-de-mar-con-muchas-posibilidades\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/preciosa-finca-con-vistas-al-mar-en-camp-de-mar-con-muchas-posibilidades\/\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/themes\/wpresidence\/img\/defaults\/default_property_listings.jpg\" class=\"b-lazy img-responsive wp-post-image  lazy-hidden\" alt=imagen del usuario\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/preciosa-finca-con-vistas-al-mar-en-camp-de-mar-con-muchas-posibilidades\/\" target=\"_self\">\n                Preciosa finca con vistas al mar en Camp de Mar con muchas posibilidades                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>6<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>390 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>7201 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">6.480.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5420-66<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/camp-de-mar-es\/\" rel=\"tag\">Camp de Mar<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1226365\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/apartamento-con-encanto-vistas-a-la-montana-y-piscina-en-establiments-palma-de-mallorca\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/apartamento-con-encanto-vistas-a-la-montana-y-piscina-en-establiments-palma-de-mallorca\/\" target=\"_self\"><img fetchpriority=\"high\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/12\/ed9e9871-9454-4291-a91d-2fe8e9e3cbc1-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5303 Apartment Establiments25\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/12\/ed9e9871-9454-4291-a91d-2fe8e9e3cbc1-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/apartamento-con-encanto-vistas-a-la-montana-y-piscina-en-establiments-palma-de-mallorca\/\" target=\"_self\">\n                Apartamento con encanto, vistas a la monta\u00f1a y piscina en Establiments, Palma de Mallorca                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>190 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1503 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">1.200.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5303-123<\/div><div class=\"propertyArea\">, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/establiments-es\/\" rel=\"tag\">Establiments<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1143819\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/encantadora-finca-en-andratx-con-piscina-mucha-privacidad-y-vistas-lejanas-al-mar\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/encantadora-finca-en-andratx-con-piscina-mucha-privacidad-y-vistas-lejanas-al-mar\/\" target=\"_self\"><img decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/390f42f8-b637-4331-828c-5892591a7b34-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"F-4366-98 Charmante Finca in Andratx mit Pool, viel Privatsph\u00e4re und Fern-Meerblick\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/390f42f8-b637-4331-828c-5892591a7b34-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/encantadora-finca-en-andratx-con-piscina-mucha-privacidad-y-vistas-lejanas-al-mar\/\" target=\"_self\">\n                Encantadora finca en Andratx con piscina, mucha privacidad y vistas lejanas al mar                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>496 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>62507 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">3.900.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">F-4366-98<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/andratx-es\/\" rel=\"tag\">Andratx<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1216151\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/impresionante-chalet-en-son-font-con-impresionantes-vistas-hasta-el-mar\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/impresionante-chalet-en-son-font-con-impresionantes-vistas-hasta-el-mar\/\" target=\"_self\"><img decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/01\/97798051-3b86-41cf-91c9-e09b82fcdcc5-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"V-3141, Son Font17\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/01\/97798051-3b86-41cf-91c9-e09b82fcdcc5-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/impresionante-chalet-en-son-font-con-impresionantes-vistas-hasta-el-mar\/\" target=\"_self\">\n                Impresionante chalet en Son Font con impresionantes vistas hasta el mar                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>508 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>4130 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">6.300.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">V-3141<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/son-font-es\/\" rel=\"tag\">Son Font<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1250280\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/fantastica-villa-mediterranea-en-primera-linea-de-mar-con-gran-piscina-y-acceso-privado-al-mar\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/fantastica-villa-mediterranea-en-primera-linea-de-mar-con-gran-piscina-y-acceso-privado-al-mar\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/08\/fe4aa1d2-54cf-4d1c-b4b2-ec6dc50e2dd7-1-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"Villa in Torrenova34\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/08\/fe4aa1d2-54cf-4d1c-b4b2-ec6dc50e2dd7-1-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/fantastica-villa-mediterranea-en-primera-linea-de-mar-con-gran-piscina-y-acceso-privado-al-mar\/\" target=\"_self\">\n                Fant\u00e1stica villa mediterr\u00e1nea en primera l\u00ednea de mar con gran piscina y acceso privado al mar                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>6<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>6<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>487 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1464 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">8.200.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">V-3726<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/palmanova-es\/\" rel=\"tag\">Palmanova<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1292857\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/adosado-reformado-con-piscina-privada-en-santa-ponsa\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/adosado-reformado-con-piscina-privada-en-santa-ponsa\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bf1d5ed7-c425-42cb-bb63-a85fbc5df02e-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5504 - Semi detached house in santa ponsa 30\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bf1d5ed7-c425-42cb-bb63-a85fbc5df02e-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/adosado-reformado-con-piscina-privada-en-santa-ponsa\/\" target=\"_self\">\n                Adosado reformado en venta en Santa Ponsa con piscina comunitaria                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>198 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">1.580.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5504 - 128<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/santa-ponsa-es\/\" rel=\"tag\">Santa Ponsa<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1001638\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/primera-compra-impresionante-villa-de-nueva-construccion-en-portals-nous-con-vistas-al-mar\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/primera-compra-impresionante-villa-de-nueva-construccion-en-portals-nous-con-vistas-al-mar\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/07\/e6dbf5e9-4c3a-4cc2-ab44-c61452c5824f-1-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"V-4697 ERSTBEZUG! Beeindruckende Neubau Villa in Portals Nous mit herrlichem Meerblick\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/07\/e6dbf5e9-4c3a-4cc2-ab44-c61452c5824f-1-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/primera-compra-impresionante-villa-de-nueva-construccion-en-portals-nous-con-vistas-al-mar\/\" target=\"_self\">\n                Impresionante villa de nueva construcci\u00f3n en Portals Nous con impresionantes vistas al mar                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>351 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>679 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">5.500.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">V-4697<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/portals-nous-es\/\" rel=\"tag\">Portals Nous<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1001540\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-finca-de-nueva-construccion-con-piscina-y-vistas-panoramicas-cerca-de-lloret-de-vistalegre\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-finca-de-nueva-construccion-con-piscina-y-vistas-panoramicas-cerca-de-lloret-de-vistalegre\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2023\/07\/e191cdbe-9f37-46d8-a35b-bfc37110fba4-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"F-3973 PROJEKT! Neubau Finca mit Infinitypool und Panoramablick nahe Lloret de Vistalegre\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2023\/07\/e191cdbe-9f37-46d8-a35b-bfc37110fba4-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><div class=\"ribbon-inside project\">project<\/div><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-finca-de-nueva-construccion-con-piscina-y-vistas-panoramicas-cerca-de-lloret-de-vistalegre\/\" target=\"_self\">\n                \u00a1PROYECTO! Finca nueva con piscina infinita y vistas panor\u00e1micas cerca de Lloret de Vistalegre                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>264 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>14630 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">2.550.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">F-3973<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/centro-de-la-isla\/\" rel=\"tag\">Centro de la isla<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/lloret-de-vista-alegre-es\/\" rel=\"tag\">Lloret de Vista Alegre<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"960216\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/primera-compra-villa-unica-de-estilo-finca-moderna-con-piscina-y-mucha-privacidad-en-es-capdella\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/primera-compra-villa-unica-de-estilo-finca-moderna-con-piscina-y-mucha-privacidad-en-es-capdella\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/bc3ccb5c-8c10-44ee-86f2-b945e4dffc5f-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"V-4676 ERSTBEZUG!!! Einzigartige moderne Villa im Finca Stil mit Pool und viel Privatsph\u00e4re in Es Capdella\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/bc3ccb5c-8c10-44ee-86f2-b945e4dffc5f-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/primera-compra-villa-unica-de-estilo-finca-moderna-con-piscina-y-mucha-privacidad-en-es-capdella\/\" target=\"_self\">\n                Villa \u00fanica en Es Capdella con piscina y mucha privacidad                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>518 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1910 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">4.500.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">V-4676<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/capdella-es\/\" rel=\"tag\">Capdella<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1100930\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/primera-ocupacion-elegante-atico-duplex-en-palma-cerca-de-santa-catalina-con-terraza-privada\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/primera-ocupacion-elegante-atico-duplex-en-palma-cerca-de-santa-catalina-con-terraza-privada\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bcc2a13f-9d76-4979-89e5-8451c5a27196-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"4980-119 ERSTBEZUG! Stylisches Duplex-Penthaus in Palma, nah zu Santa Catalina, mit privater Terrasse 7\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bcc2a13f-9d76-4979-89e5-8451c5a27196-2-525x328.jpg\" srcset=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bcc2a13f-9d76-4979-89e5-8451c5a27196-2-525x328.jpg 525w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bcc2a13f-9d76-4979-89e5-8451c5a27196-2-1200x749.jpg 1200w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bcc2a13f-9d76-4979-89e5-8451c5a27196-2-1900x1187.jpg 1900w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bcc2a13f-9d76-4979-89e5-8451c5a27196-2-600x375.jpg 600w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bcc2a13f-9d76-4979-89e5-8451c5a27196-2-768x480.jpg 768w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bcc2a13f-9d76-4979-89e5-8451c5a27196-2-1536x959.jpg 1536w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/bcc2a13f-9d76-4979-89e5-8451c5a27196-2.jpg 1920w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/primera-ocupacion-elegante-atico-duplex-en-palma-cerca-de-santa-catalina-con-terraza-privada\/\" target=\"_self\">\n                \u00a1PRIMERA OCUPACI\u00d3N! Elegante \u00e1tico d\u00faplex Santa Catalina en venta, con terraza privada                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>95 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">529.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">4980-119<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/palma-y-alrededores\/\" rel=\"tag\">Palma y alrededores<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/palma-es\/\" rel=\"tag\">Palma<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1301141\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/encantadora-casa-con-piscina-y-jardin-en-cala-blava-bellavista\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/encantadora-casa-con-piscina-y-jardin-en-cala-blava-bellavista\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/5bd8004d-a796-4d40-b302-5356dd3647ed-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5552 - Villa in Cala Blava 8\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/5bd8004d-a796-4d40-b302-5356dd3647ed-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/encantadora-casa-con-piscina-y-jardin-en-cala-blava-bellavista\/\" target=\"_self\">\n                Encantadora casa con piscina y jard\u00edn en Cala Blava, Bellavista                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>988 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">955.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5552<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sur\/\" rel=\"tag\">Sur<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/bahia-blava-es\/\" rel=\"tag\">Bahia Blava<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1255140\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/amplio-chalet-en-sa-torre-con-licencia-de-alquiler-vacacional-vistas-al-mar-y-mucho-potencial\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/amplio-chalet-en-sa-torre-con-licencia-de-alquiler-vacacional-vistas-al-mar-y-mucho-potencial\/\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/themes\/wpresidence\/img\/defaults\/default_property_listings.jpg\" class=\"b-lazy img-responsive wp-post-image  lazy-hidden\" alt=imagen del usuario\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><div class=\"ribbon-inside holiday-rental-licence\">Holiday rental licence<\/div><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/amplio-chalet-en-sa-torre-con-licencia-de-alquiler-vacacional-vistas-al-mar-y-mucho-potencial\/\" target=\"_self\">\n                Amplio chalet en venta en Sa Torre con licencia de alquiler vacacional, vistas al mar y mucho potencial                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>583 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1807 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">3.000.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">V-3515<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sur\/\" rel=\"tag\">Sur<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/sa-torre-es\/\" rel=\"tag\">Sa Torre<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1224147\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/atico-unico-en-port-andratx-con-vistas-al-mar\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/atico-unico-en-port-andratx-con-vistas-al-mar\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/3ccbf3ce-0a5a-4f8a-b0be-471486895185-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5288 Penthouse in Port Andratx21\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/3ccbf3ce-0a5a-4f8a-b0be-471486895185-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/atico-unico-en-port-andratx-con-vistas-al-mar\/\" target=\"_self\">\n                \u00c1tico \u00fanico en venta en Port Andratx con vistas al mar                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>242 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">1.980.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5288-66<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/port-andratx-es\/\" rel=\"tag\">Port Andratx<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1255747\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/parcela-con-proyecto-y-licencia-de-obra-en-cas-concos-con-vistas-hasta-la-sierra-de-tramuntana\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/parcela-con-proyecto-y-licencia-de-obra-en-cas-concos-con-vistas-hasta-la-sierra-de-tramuntana\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/ec946f4e-d29b-4744-b577-eeed0108ac3e-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5414 - Projekt in Cas Concos2\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/ec946f4e-d29b-4744-b577-eeed0108ac3e-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><div class=\"ribbon-inside project\">project<\/div><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/parcela-con-proyecto-y-licencia-de-obra-en-cas-concos-con-vistas-hasta-la-sierra-de-tramuntana\/\" target=\"_self\">\n                Parcela con proyecto y licencia de obra en Cas Concos con vistas hasta la Sierra de Tramuntana                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>25467 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">429.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5414<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/cas-concos-es\/\" rel=\"tag\">Cas Concos<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1290133\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/elegante-atico-en-sa-rapita-con-azotea-y-vistas-al-mar\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/elegante-atico-en-sa-rapita-con-azotea-y-vistas-al-mar\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/f4b08daa-7cf9-401e-b3b9-698ba4c2f97d-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"P-4246_4 Elegantes Penthouse in Sa R\u00e0pita mit Dachterrasse und Meerblick\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/04\/f4b08daa-7cf9-401e-b3b9-698ba4c2f97d-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/elegante-atico-en-sa-rapita-con-azotea-y-vistas-al-mar\/\" target=\"_self\">\n                Elegante \u00e1tico en Sa R\u00e0pita con azotea y vistas al mar                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>260 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">899.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">P-4246_4<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/sa-rapita-es\/\" rel=\"tag\">Sa Rapita<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"619753\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-de-ensueno-con-piscina-y-mucha-privacidad-en-la-hermosa-nova-santa-ponca\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-de-ensueno-con-piscina-y-mucha-privacidad-en-la-hermosa-nova-santa-ponca\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/04\/44e0b9de-5f20-4d28-a003-1fd523d4a725-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"V-4135 NEUBAU! Ruhig gelegene Traum-Villa in Nova Santa Pon\u00e7a mit Pool, Garten und Privatsph\u00e4re 1\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/04\/44e0b9de-5f20-4d28-a003-1fd523d4a725-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-de-ensueno-con-piscina-y-mucha-privacidad-en-la-hermosa-nova-santa-ponca\/\" target=\"_self\">\n                Villa renovada de alta calidad en Nova Santa Ponsa, en un lugar tranquilo y privado                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>6<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>408 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1561 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">4.495.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">V-4135<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/santa-ponsa-es\/\" rel=\"tag\">Santa Ponsa<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"772154\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-fantastica-finca-de-nueva-construccion-con-vistas-panoramicas-entre-ses-salines-y-es-llombards\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-fantastica-finca-de-nueva-construccion-con-vistas-panoramicas-entre-ses-salines-y-es-llombards\/\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/themes\/wpresidence\/img\/defaults\/default_property_listings.jpg\" class=\"b-lazy img-responsive wp-post-image  lazy-hidden\" alt=imagen del usuario\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-fantastica-finca-de-nueva-construccion-con-vistas-panoramicas-entre-ses-salines-y-es-llombards\/\" target=\"_self\">\n                Finca de lujo entre Ses Salines y Es Llombards con fant\u00e1sticas vistas panor\u00e1micas                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>450 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>15000 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">4.900.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">F-4055<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/ses-salines-es\/\" rel=\"tag\">Ses Salines<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1285240\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-de-lujo-con-licencia-de-alquiler-en-can-pastilla\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-de-lujo-con-licencia-de-alquiler-en-can-pastilla\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/5e1c8a88-acc2-4a61-bde9-2759a260f969-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"ETV LOGO PPM  (2)\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/5e1c8a88-acc2-4a61-bde9-2759a260f969-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><div class=\"ribbon-inside holiday-rental-licence\">Holiday rental licence<\/div><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-de-lujo-con-licencia-de-alquiler-en-can-pastilla\/\" target=\"_self\">\n                Villa de lujo con licencia de alquiler en Can Pastilla                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>7<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>417 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>727 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">1.600.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5468<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/palma-y-alrededores\/\" rel=\"tag\">Palma y alrededores<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/playa-de-palma-es\/\" rel=\"tag\">Playa de Palma<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1168132\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/excepcional-finca-en-santanyi-con-un-diseno-moderno-y-privacidad-absoluta\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/excepcional-finca-en-santanyi-con-un-diseno-moderno-y-privacidad-absoluta\/\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/themes\/wpresidence\/img\/defaults\/default_property_listings.jpg\" class=\"b-lazy img-responsive wp-post-image  lazy-hidden\" alt=imagen del usuario\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/excepcional-finca-en-santanyi-con-un-diseno-moderno-y-privacidad-absoluta\/\" target=\"_self\">\n                Excepcional finca en Santanyi con un dise\u00f1o moderno y privacidad absoluta                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>1045 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>53567 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">5.490.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5158<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/santanyi-es\/\" rel=\"tag\">Santanyi<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1140348\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/chalet-de-nueva-construccion-en-santa-ponsa-en-una-parcela-espaciosa-y-de-primera-calidad\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/chalet-de-nueva-construccion-en-santa-ponsa-en-una-parcela-espaciosa-y-de-primera-calidad\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/8dddbf2a-b770-4211-8760-2b027ac72dba-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5101 Neubau Villa in Santa Ponsa auf gro\u00dfz\u00fcgigem Grundst\u00fcck und bester Qualit\u00e4t 1\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/8dddbf2a-b770-4211-8760-2b027ac72dba-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/chalet-de-nueva-construccion-en-santa-ponsa-en-una-parcela-espaciosa-y-de-primera-calidad\/\" target=\"_self\">\n                Chalet de nueva construcci\u00f3n en Santa Ponsa en una parcela espaciosa y de primera calidad                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>6<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>1000 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>2030 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">12.000.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5101<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/santa-ponsa-es\/\" rel=\"tag\">Santa Ponsa<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1061463\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-casa-de-pueblo-unica-en-estilo-finca-con-gran-jardin-y-piscina-en-ses-salines\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-casa-de-pueblo-unica-en-estilo-finca-con-gran-jardin-y-piscina-en-ses-salines\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/7baea2f1-6115-471a-837c-a233462b95e5-1-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"D-4686 Einzigartiges Dorfhaus in Ses Salines mit riesigem Garten &amp; Pool\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/7baea2f1-6115-471a-837c-a233462b95e5-1-525x328.jpg\" srcset=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/7baea2f1-6115-471a-837c-a233462b95e5-1-525x328.jpg 525w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/7baea2f1-6115-471a-837c-a233462b95e5-1-1200x750.jpg 1200w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/7baea2f1-6115-471a-837c-a233462b95e5-1-1900x1188.jpg 1900w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/7baea2f1-6115-471a-837c-a233462b95e5-1-600x375.jpg 600w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/7baea2f1-6115-471a-837c-a233462b95e5-1-768x480.jpg 768w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/7baea2f1-6115-471a-837c-a233462b95e5-1-1536x960.jpg 1536w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/04\/7baea2f1-6115-471a-837c-a233462b95e5-1.jpg 1920w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-casa-de-pueblo-unica-en-estilo-finca-con-gran-jardin-y-piscina-en-ses-salines\/\" target=\"_self\">\n                Casa de pueblo \u00fanica en Ses Salines con gran jard\u00edn y piscina                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>375 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>360 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">3.150.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">D-4686<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/ses-salines-es\/\" rel=\"tag\">Ses Salines<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1100053\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/excepcional-villa-de-nueva-construccion-con-impresionantes-vistas-parciales-al-mar-en-cala-vinyas-mallorca\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/excepcional-villa-de-nueva-construccion-con-impresionantes-vistas-parciales-al-mar-en-cala-vinyas-mallorca\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7aa827e9-0ccc-4475-a3c6-af62bd0c604d-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"V-4840 Au\u00dfergew\u00f6hnliche neu gebaute Villa mit herrlichem Teilmeerblick in Cala Vinyas, Mallorca\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7aa827e9-0ccc-4475-a3c6-af62bd0c604d-2-525x328.jpg\" srcset=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7aa827e9-0ccc-4475-a3c6-af62bd0c604d-2-525x328.jpg 525w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7aa827e9-0ccc-4475-a3c6-af62bd0c604d-2-1200x749.jpg 1200w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7aa827e9-0ccc-4475-a3c6-af62bd0c604d-2-600x375.jpg 600w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7aa827e9-0ccc-4475-a3c6-af62bd0c604d-2-768x480.jpg 768w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7aa827e9-0ccc-4475-a3c6-af62bd0c604d-2-1536x959.jpg 1536w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7aa827e9-0ccc-4475-a3c6-af62bd0c604d-2.jpg 1640w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/excepcional-villa-de-nueva-construccion-con-impresionantes-vistas-parciales-al-mar-en-cala-vinyas-mallorca\/\" target=\"_self\">\n                Excepcional villa de nueva construcci\u00f3n con impresionantes vistas parciales al mar en Cala Vinyas, Mallorca                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>547 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1450 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">5.950.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">V-4840<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/cala-vinyas-es\/\" rel=\"tag\">Cala Vinyas<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1130447\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-lujoso-atico-en-santa-ponca-con-terraza-piscina-privada-y-vistas-al-mar\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-lujoso-atico-en-santa-ponca-con-terraza-piscina-privada-y-vistas-al-mar\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/09\/60876030-4e5c-445d-aaa1-aa0c19e46d44-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"P-3109_24 PROJEKT! Luxuri\u00f6ses Penthouse in Santa Pon\u00e7a mit privater Pool-Terrasse und Meerblick\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/09\/60876030-4e5c-445d-aaa1-aa0c19e46d44-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-lujoso-atico-en-santa-ponca-con-terraza-piscina-privada-y-vistas-al-mar\/\" target=\"_self\">\n                \u00a1PROYECTO! Lujoso \u00e1tico en Santa Pon\u00e7a con terraza piscina privada y vistas al mar                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>155 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">2.850.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">P-3109_24<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/santa-ponsa-es\/\" rel=\"tag\">Santa Ponsa<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1276807\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-moderna-con-piscina-y-vistas-al-mar-en-una-zona-tranquila-de-santa-ponsa\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-moderna-con-piscina-y-vistas-al-mar-en-una-zona-tranquila-de-santa-ponsa\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/f3aa6b95-a479-43f3-8c7a-eada32a77eae-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"4219 Villa with pool and sea view in a quiet area of Santa Ponsa23\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/f3aa6b95-a479-43f3-8c7a-eada32a77eae-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-moderna-con-piscina-y-vistas-al-mar-en-una-zona-tranquila-de-santa-ponsa\/\" target=\"_self\">\n                Villa moderna con piscina y vistas al mar en una zona tranquila de Santa Ponsa                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>456 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1276 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">3.650.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">4219<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/santa-ponsa-es\/\" rel=\"tag\">Santa Ponsa<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1100336\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-mediterranea-de-lujo-con-vistas-panoramicas-en-la-codiciada-zona-residencial-de-nova-santa-ponsa\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-mediterranea-de-lujo-con-vistas-panoramicas-en-la-codiciada-zona-residencial-de-nova-santa-ponsa\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7f3cd4ed-d158-4f5e-a04c-66eb7ca55912-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"4905 Mediterrane Luxus-Villa mit Panoramablick, in begehrter Wohnlage von Nova Santa Ponsa\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7f3cd4ed-d158-4f5e-a04c-66eb7ca55912-2-525x328.jpg\" srcset=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7f3cd4ed-d158-4f5e-a04c-66eb7ca55912-2-525x328.jpg 525w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7f3cd4ed-d158-4f5e-a04c-66eb7ca55912-2-1200x749.jpg 1200w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7f3cd4ed-d158-4f5e-a04c-66eb7ca55912-2-600x375.jpg 600w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7f3cd4ed-d158-4f5e-a04c-66eb7ca55912-2-768x480.jpg 768w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7f3cd4ed-d158-4f5e-a04c-66eb7ca55912-2-1536x959.jpg 1536w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/02\/7f3cd4ed-d158-4f5e-a04c-66eb7ca55912-2.jpg 1640w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-mediterranea-de-lujo-con-vistas-panoramicas-en-la-codiciada-zona-residencial-de-nova-santa-ponsa\/\" target=\"_self\">\n                Villa mediterr\u00e1nea de lujo con vistas panor\u00e1micas, en la codiciada zona residencial de Nova Santa Ponsa                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>551 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1280 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">5.900.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">4905<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/santa-ponsa-es\/\" rel=\"tag\">Santa Ponsa<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1219303\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/en-construccion-noble-finca-de-lujo-en-sa-coma-bunyola-con-vistas-al-mar-y-a-la-sierra-de-tramuntana\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/en-construccion-noble-finca-de-lujo-en-sa-coma-bunyola-con-vistas-al-mar-y-a-la-sierra-de-tramuntana\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/fab307ac-6fd2-40db-97de-86340e4c6d14-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5273-125 Finca in Sa Coma - Bunyola 2\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/fab307ac-6fd2-40db-97de-86340e4c6d14-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/en-construccion-noble-finca-de-lujo-en-sa-coma-bunyola-con-vistas-al-mar-y-a-la-sierra-de-tramuntana\/\" target=\"_self\">\n                \u00a1EN CONSTRUCCI\u00d3N! Noble finca de lujo en Sa Coma &#8211; Bunyola con vistas al mar y a la Sierra de Tramuntana                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>700 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>2750 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">5.950.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5273-125<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/oeste\/\" rel=\"tag\">Oeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/bunyola-es\/\" rel=\"tag\">Bunyola<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1282160\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-finca-la-bastida-en-sa-rapita-la-perfeccion-de-la-sencillez\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-finca-la-bastida-en-sa-rapita-la-perfeccion-de-la-sencillez\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/3fbc3f86-f8fb-4636-8acd-4e4e01d5a60a-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"secretmarketing\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/3fbc3f86-f8fb-4636-8acd-4e4e01d5a60a-2-525x328.jpg\" srcset=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/3fbc3f86-f8fb-4636-8acd-4e4e01d5a60a-2-525x328.jpg 525w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/3fbc3f86-f8fb-4636-8acd-4e4e01d5a60a-2-1200x749.jpg 1200w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/3fbc3f86-f8fb-4636-8acd-4e4e01d5a60a-2-600x375.jpg 600w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/3fbc3f86-f8fb-4636-8acd-4e4e01d5a60a-2-768x480.jpg 768w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/3fbc3f86-f8fb-4636-8acd-4e4e01d5a60a-2-1536x959.jpg 1536w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/11\/3fbc3f86-f8fb-4636-8acd-4e4e01d5a60a-2.jpg 1640w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><div class=\"ribbon-inside project\">project<\/div><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-finca-la-bastida-en-sa-rapita-la-perfeccion-de-la-sencillez\/\" target=\"_self\">\n                Nuevo proyecto de finca en Sa Rapita &#8211; La perfecci\u00f3n de la sencillez                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>7<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>10<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>18000 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">9.700.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5446<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/sa-rapita-es\/\" rel=\"tag\">Sa Rapita<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"741590\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/imponente-villa-con-licencia-de-alquiler-vacacional-y-vistas-al-valle-asi-como-al-campo-de-golf-de-canyamel\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/imponente-villa-con-licencia-de-alquiler-vacacional-y-vistas-al-valle-asi-como-al-campo-de-golf-de-canyamel\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/94f59391-e67b-4099-95d9-19c888be450b-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"ETV LOGO PPM  (3)\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/94f59391-e67b-4099-95d9-19c888be450b-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><div class=\"ribbon-inside holiday-rental-licence\">Holiday rental licence<\/div><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/imponente-villa-con-licencia-de-alquiler-vacacional-y-vistas-al-valle-asi-como-al-campo-de-golf-de-canyamel\/\" target=\"_self\">\n                Imponente villa con licencia de alquiler vacacional y vistas al valle, as\u00ed como al campo de golf de Canyamel                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>443 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1440 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">4.850.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">V-2078<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/noreste\/\" rel=\"tag\">Noreste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/canyamel-es\/\" rel=\"tag\">Canyamel<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"477214\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-mediterranea-en-primera-linea-de-mar-en-la-playa-de-port-de-soller\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-mediterranea-en-primera-linea-de-mar-en-la-playa-de-port-de-soller\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2021\/04\/Foto_158065-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"V-2742, Port de Soller\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2021\/04\/Foto_158065-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/villa-mediterranea-en-primera-linea-de-mar-en-la-playa-de-port-de-soller\/\" target=\"_self\">\n                Villa mediterr\u00e1nea en primera l\u00ednea de mar en la playa de Port de S\u00f3ller                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>6<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>382 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>400 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">3.500.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">V-2742<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/oeste\/\" rel=\"tag\">Oeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/soller-es\/\" rel=\"tag\">Soller<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1297188\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/casas-de-obra-nueva-en-cala-romantica-casa-adosada-o-chalet-con-extras-reservables\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/casas-de-obra-nueva-en-cala-romantica-casa-adosada-o-chalet-con-extras-reservables\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/14fedb81-5451-4d2c-b1c6-e8966c331a24-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"2- Piscina (1)\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/14fedb81-5451-4d2c-b1c6-e8966c331a24-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/casas-de-obra-nueva-en-cala-romantica-casa-adosada-o-chalet-con-extras-reservables\/\" target=\"_self\">\n                Casas de obra nueva en venta en Cala Romantica &#8211; casa adosada o chalet con extras reservables                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>237 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">399.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5336<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/cala-romantica-es\/\" rel=\"tag\">Cala Romantica<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1225544\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-de-chalet-unico-en-alaro\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-de-chalet-unico-en-alaro\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/06\/43dbb256-0908-478a-8dde-ecc47417c5df-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"_11-01_Piscina002_20\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/06\/43dbb256-0908-478a-8dde-ecc47417c5df-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/proyecto-de-chalet-unico-en-alaro\/\" target=\"_self\">\n                Proyecto de chalet \u00fanico en Alar\u00f3                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>362 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>23000 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">5.750.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5299 -126<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/centro-de-la-isla\/\" rel=\"tag\">Centro de la isla<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/alaro-es\/\" rel=\"tag\">Alaro<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1226386\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/parcela-con-proyecto-para-una-villa-unica-en-puerto-andratx\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/parcela-con-proyecto-para-una-villa-unica-en-puerto-andratx\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/06\/d1d6c340-ef96-45a3-918a-1b423dfb6353-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5307 - 66 Grundst\u00fcck mit Projekt in Port Andratx1\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/06\/d1d6c340-ef96-45a3-918a-1b423dfb6353-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/parcela-con-proyecto-para-una-villa-unica-en-puerto-andratx\/\" target=\"_self\">\n                Parcela con proyecto para una villa \u00fanica en Puerto Andratx                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>6<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>784 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1338 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">3.480.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5307 - 66<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/port-andratx-es\/\" rel=\"tag\">Port Andratx<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1096574\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/inversion-impresionante-casa-en-primera-linea-en-calanova-con-impresionantes-vistas-al-mar\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/inversion-impresionante-casa-en-primera-linea-en-calanova-con-impresionantes-vistas-al-mar\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/01\/9c47091a-6806-40e7-bfbd-304324edd476-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"4949 INVESTITION!  Beeindruckendes Haus in erster Linie in Calanova mit herrlichem Meerblick\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2024\/01\/9c47091a-6806-40e7-bfbd-304324edd476-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/inversion-impresionante-casa-en-primera-linea-en-calanova-con-impresionantes-vistas-al-mar\/\" target=\"_self\">\n                \u00a1INVERSION! Casa en Cala Nova, primera l\u00ednea con magn\u00edficas vistas al puerto y al mar                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>11<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>532 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>364 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">3.500.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">4949<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/palma-y-alrededores\/\" rel=\"tag\">Palma y alrededores<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/san-agustin-es\/\" rel=\"tag\">San Agustin<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1294735\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/preciosa-finca-en-llucmajor-un-paraiso-subtropical-para-relajarse\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/preciosa-finca-en-llucmajor-un-paraiso-subtropical-para-relajarse\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/42d07e89-420a-43d7-a3a7-a81e033e90dd-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5199- Finca in Llucmajor 40\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/42d07e89-420a-43d7-a3a7-a81e033e90dd-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/preciosa-finca-en-llucmajor-un-paraiso-subtropical-para-relajarse\/\" target=\"_self\">\n                Hermosa finca en venta en Llucmajor &#8211; Un para\u00edso subtropical para relajarse                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>255 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1170 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">1.295.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5199<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sur\/\" rel=\"tag\">Sur<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/llucmajor-es\/\" rel=\"tag\">Llucmajor<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1283639\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/precioso-chalet-con-licencia-de-alquiler-en-cala-dor\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/precioso-chalet-con-licencia-de-alquiler-en-cala-dor\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/2d3f54bb-b348-4856-a81f-81e8c4a59fe1-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"ing_2356\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/2d3f54bb-b348-4856-a81f-81e8c4a59fe1-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><div class=\"ribbon-inside holiday-rental-licence\">Holiday rental licence<\/div><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/precioso-chalet-con-licencia-de-alquiler-en-cala-dor\/\" target=\"_self\">\n                Precioso chalet con licencia de alquiler en Cala d&#8217;Or                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>260 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>1083 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">2.000.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5473<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/cala-dor-es-2\/\" rel=\"tag\">Cala D'or<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1052230\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/idilica-finca-de-piedra-natural-con-piscina-y-vistas-entre-campos-y-santanyi-ideal-para-los-amantes-de-la-naturaleza\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/idilica-finca-de-piedra-natural-con-piscina-y-vistas-entre-campos-y-santanyi-ideal-para-los-amantes-de-la-naturaleza\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/e7b24c2d-acdb-4874-8f12-fa08c240fdaa-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"ETV LOGO PPM  (4)\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/03\/e7b24c2d-acdb-4874-8f12-fa08c240fdaa-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><div class=\"ribbon-inside holiday-rental-licence\">Holiday rental licence<\/div><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/idilica-finca-de-piedra-natural-con-piscina-y-vistas-entre-campos-y-santanyi-ideal-para-los-amantes-de-la-naturaleza\/\" target=\"_self\">\n                Finca de piedra con piscina y vistas entre Campos y Santany\u00ed, \u00a1ideal para los amantes de la naturaleza!                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>3<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>250 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>11000 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">1.590.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">F-2087<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/campos-es\/\" rel=\"tag\">Campos<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1144751\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/atico-duplex-en-palma-con-enorme-terraza-e-impresionantes-vistas\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/atico-duplex-en-palma-con-enorme-terraza-e-impresionantes-vistas\/\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/themes\/wpresidence\/img\/defaults\/default_property_listings.jpg\" class=\"b-lazy img-responsive wp-post-image  lazy-hidden\" alt=imagen del usuario\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/atico-duplex-en-palma-con-enorme-terraza-e-impresionantes-vistas\/\" target=\"_self\">\n                \u00c1tico d\u00faplex en venta en Palma con gran terraza e impresionantes vistas                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>2<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>208 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>0 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">2.950.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5130-125<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/palma-y-alrededores\/\" rel=\"tag\">Palma y alrededores<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/palma-oldtown-es-2\/\" rel=\"tag\">Palma Oldtown<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1289998\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/preciosa-villa-directamente-en-el-campo-de-golf-de-santa-ponsa\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/preciosa-villa-directamente-en-el-campo-de-golf-de-santa-ponsa\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/01\/ec91e33b-be5b-404d-b36c-717345ebfcd6-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"5494 - Villa in Santa Ponsa 30\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2026\/01\/ec91e33b-be5b-404d-b36c-717345ebfcd6-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/preciosa-villa-directamente-en-el-campo-de-golf-de-santa-ponsa\/\" target=\"_self\">\n                Preciosa villa directamente en el campo de golf de Santa Ponsa                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>7<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>9<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>913 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>2135 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">8.900.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5494<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/suroeste\/\" rel=\"tag\">Suroeste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/santa-ponsa-es\/\" rel=\"tag\">Santa Ponsa<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1100375\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/agroturismo-finca-con-maravillosas-vistas-piscina-y-licencia-entre-campos-sa-rapita-en-el-sureste\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/agroturismo-finca-con-maravillosas-vistas-piscina-y-licencia-entre-campos-sa-rapita-en-el-sureste\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/09\/43af71a4-6362-4a7b-b7bf-70d194d411f2-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"ETV LOGO PPM  (2)\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/09\/43af71a4-6362-4a7b-b7bf-70d194d411f2-2-525x328.jpg\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><div class=\"ribbon-inside holiday-rental-licence\">Holiday rental licence<\/div><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/agroturismo-finca-con-maravillosas-vistas-piscina-y-licencia-entre-campos-sa-rapita-en-el-sureste\/\" target=\"_self\">\n                Agroturismo-Finca con maravillosas vistas, piscina y licencia entre Campos\/Sa Rapita en el sureste                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>8<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>7<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>1100 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>42095 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">5.325.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">H-4791<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/campos-es\/\" rel=\"tag\">Campos<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n  \n\n\n\n<div class=\"col-md-3 shortcode-col has_4per_row  listing_wrapper property_unit_type2\" data-org=\"4\" data-listid=\"1222072\" > \n    <div class=\"property_listing property_unit_type2  \" data-link=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/finca-de-lujo-de-nueva-construccion-en-ses-salines-con-mucha-privacidad\/\">\n        \n        <div class=\"listing-unit-img-wrapper\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/finca-de-lujo-de-nueva-construccion-en-ses-salines-con-mucha-privacidad\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/bda66257-3548-4dc7-8282-40f5ec15801c-2-525x328.jpg\" class=\"lazyload img-responsive wp-post-image\" alt=\"secretmarketing\" data-original=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/bda66257-3548-4dc7-8282-40f5ec15801c-2-525x328.jpg\" srcset=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/bda66257-3548-4dc7-8282-40f5ec15801c-2-525x328.jpg 525w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/bda66257-3548-4dc7-8282-40f5ec15801c-2-1200x749.jpg 1200w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/bda66257-3548-4dc7-8282-40f5ec15801c-2-600x375.jpg 600w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/bda66257-3548-4dc7-8282-40f5ec15801c-2-768x480.jpg 768w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/bda66257-3548-4dc7-8282-40f5ec15801c-2-1536x959.jpg 1536w, https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2025\/05\/bda66257-3548-4dc7-8282-40f5ec15801c-2.jpg 1640w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/a><div class=\"tag-wrapper\"><div class=\"status-wrapper\"><\/div><\/div><\/div>\n\n            <h4><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/propiedades\/finca-de-lujo-de-nueva-construccion-en-ses-salines-con-mucha-privacidad\/\" target=\"_self\">\n                Finca de lujo de nueva construcci\u00f3n en Ses Salines con mucha privacidad                <\/a> \n            <\/h4> \n        \n            <div class=\"property_listing_details\">\n                <div class=\"smallCol\"><div class=\"inforoom_unit_type2\"><\/div><div>5<\/div><\/div><div class=\"smallCol\"><div class=\"infobath_unit_type2\"><\/div><div>4<\/div><\/div><div class=\"smallCol\"><div class=\"infosize_unit_type2\"><\/div><div>680 m&sup2;<\/div><\/div><div class=\"smallCol\"><div class=\"infolotsize_unit_type2\"><\/div><div>16580 m&sup2;<\/div><\/div>            <\/div>\n\t\t\n            <div class=\"listing_unit_price_wrapper\">4.295.000 \u20ac <span class=\"price_label\"><\/span><\/div>               \n            <div class=\"property_location\">\n                    \n                    <div class=\"ownerNotes\">5278<\/div><div class=\"propertyArea\"><a href=\"https:\/\/www.privatepropertymallorca.com\/es\/state\/sureste\/\" rel=\"tag\">Sureste<\/a>, <a href=\"https:\/\/www.privatepropertymallorca.com\/es\/ort\/ses-salines-es\/\" rel=\"tag\">Ses Salines<\/a><\/div>                        <\/div>        <\/div>             \n    <\/div>\n<div class=\"wpestate_listing_sh_loader\">\n       <div class=\"new_prelader\"><\/div>\n\n    <\/div><div class=\"listinglink-wrapper_sh_listings\">\n               <span class=\"wpresidence_button wpestate_item_list_sh\">cargar m\u00e1s inmuebles <\/span>\n               <\/div><\/div><script type=\"text\/javascript\">\n                \/\/<![CDATA[\n                jQuery(document).ready(function(){\n                  \/\/  wpestate_anime(\"#wpestate_sh_anime_789\");\n                   \/\/ wpestate_property_list_sh(\"#wpestate_sh_anime_789 .wpestate_item_list_sh\", \"#wpestate_sh_anime_789 .control_tax_sh\");\n                });\n                \/\/]]>\n            <\/script>[\/vc_column][\/vc_row]<\/p>\n<div class=\"bellvueblock \"><img decoding=\"async\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2020\/02\/best_icon-159x300.png\" alt=\"bellvue\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Mallorca suele ser estereotipada como un destino de fiesta, pero la isla es una joya del Mediterr\u00e1neo que espera ser descubierta. Lejos de la animada vida nocturna, la isla ofrece una naturaleza deslumbrante, pueblos encantadores y una creciente comunidad de entusiastas del bienestar. Este entorno id\u00edlico ofrece el escenario perfecto para el Yoga del Mar Spirit Festival, un evento que promete una experiencia transformadora.<\/p>\n","protected":false},"author":13,"featured_media":1147161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Yoga del Mar Spirit Festival: Un viaje de conexi\u00f3n en Mallorca","_seopress_titles_desc":"Mallorca suele ser estereotipada como un destino de fiesta, pero la isla es una joya del Mediterr\u00e1neo que espera ser descubierta. Lejos de la animada vida nocturna, la isla ofrece una naturaleza deslumbrante, pueblos encantadores y una creciente comunidad de entusiastas del bienestar. Este entorno id\u00edlico ofrece el escenario perfecto para el Yoga del Mar Spirit Festival, un evento que promete una experiencia transformadora.","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[1297],"tags":[2664,2665,2666,2667,2668,2669],"class_list":{"0":"post-1147158","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultura-y-ocio","8":"tag-immobile-kaufen-santa-ponsa-es","9":"tag-immobilen-auf-mallorca-kaufen-es","10":"tag-immobilen-zu-verkauf-mallorca-es","11":"tag-immobilien-auf-mallorca-es","12":"tag-immobilien-mallorca-es","13":"tag-immobilien-santa-ponsa-es"},"_links":{"self":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/posts\/1147158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/comments?post=1147158"}],"version-history":[{"count":0,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/posts\/1147158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/media\/1147161"}],"wp:attachment":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/media?parent=1147158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/categories?post=1147158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/tags?post=1147158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}