{"id":422081,"date":"2021-04-01T18:49:10","date_gmt":"2021-04-01T16:49:10","guid":{"rendered":"https:\/\/dev.privateproperty.immo\/pueblos-de-mallorca-presentamos-montuiri\/"},"modified":"2021-04-21T14:18:15","modified_gmt":"2021-04-21T12:18:15","slug":"pueblos-de-mallorca-presentamos-montuiri-2","status":"publish","type":"post","link":"https:\/\/www.privatepropertymallorca.com\/es\/revista\/pueblos-de-mallorca-presentamos-montuiri-2\/","title":{"rendered":"Finca Es Cab\u00e0s &#8211; un lugar que nunca olvidar\u00e1"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=\u00bb2\/3&#8243;]<div id=\"ultimate-heading-85336a03ccba74c97\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-85336a03ccba74c97 uvc-6808 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-85336a03ccba74c97 h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"font-weight:normal;\">Finca Es Cab\u00e0s - un lugar que nunca olvidar\u00e1<\/h2><\/div><\/div>[vc_empty_space][vc_column_text]La <a href=\"http:\/\/www.fincaescabas.com\/en\/\">Finca Es Cab\u00e0s<\/a> ha sido habitada y cultivada desde hace miles de a\u00f1os, con todos los pueblos que nos precedieron dejando su huella en la tierra. Esta antigua finca de origen talai\u00f3tico y morisco, bellamente restaurada, se encuentra a los pies de la Serra de Tramuntana a tan s\u00f3lo 15 minutos de Palma. El cortijo en s\u00ed es de origen morisco y en las cumbres que rodean la finca se encuentran otros restos de la \u00e9poca romana y talai\u00f3tica. Dejando de lado las curiosidades arqueol\u00f3gicas, se sabe que el edificio se utilizaba hist\u00f3ricamente con fines exclusivamente agr\u00edcolas, como la producci\u00f3n de aceite de oliva, la cr\u00eda de ganado y el almacenamiento. La casa ha sido restaurada con mucho gusto, manteniendo la integridad del espacio para preservar una hermosa parte de la historia de Mallorca.<\/p>\n<p>Es Cab\u00e1s ofrece a sus hu\u00e9spedes todas las comodidades modernas pero al mismo tiempo impresiona con la sensaci\u00f3n aut\u00e9ntica de tiempos pasados. Es Cab\u00e0s fue en su d\u00eda una de las fincas m\u00e1s productivas de la isla. Aunque la escala de producci\u00f3n ha disminuido dr\u00e1sticamente a lo largo de los siglos, seguimos produciendo una gama de productos ecol\u00f3gicos con m\u00e9todos tradicionales.[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb422087&#8243; img_size=\u00bbmedium\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb422094&#8243; img_size=\u00bblarge\u00bb][\/vc_column][vc_column width=\u00bb2\/3&#8243;]<div id=\"ultimate-heading-19506a03ccba74d06\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-19506a03ccba74d06 uvc-4675 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-19506a03ccba74d06 h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"font-weight:normal;\">\u00bfQu\u00e9 puede experimentar en la Finca?<\/h2><\/div><\/div>[vc_empty_space][vc_column_text]Los olivares de <a href=\"http:\/\/www.fincaescabas.com\/en\/\">Es Cab\u00e0s<\/a> est\u00e1n formados exclusivamente por aut\u00e9nticos olivos mallorquines, que s\u00f3lo proceden de un proceso de injerto y tienen cientos de a\u00f1os. De estas aut\u00e9nticas aceitunas mallorquinas, recogidas a mano, se extrae un aceite de oliva virgen extra en peque\u00f1os lotes que se embotella a pocos kil\u00f3metros de la finca. Fruto de una larga tradici\u00f3n de agricultura ecol\u00f3gica, el aceite de oliva se est\u00e1 haciendo un hueco en el sector por su pureza, su sabor y los m\u00e9todos tradicionales utilizados en su producci\u00f3n. Por supuesto, tambi\u00e9n se ofrecen catas de vino. Por supuesto, la finca tambi\u00e9n alberga muchos habitantes animales como cabras mallorquinas, burros, cerdos negros, caballos y ovejas.<\/p>\n<p>La Finca es C\u00e1bas es un lugar de tranquilidad y los actuales propietarios no han escatimado esfuerzos para ofrecer a los hu\u00e9spedes una visi\u00f3n real de las ra\u00edces y tradiciones agr\u00edcolas de Mallorca. La finca le invita a dar largos paseos, a descubrir la naturaleza de Mallorca en su m\u00e1xima expresi\u00f3n o a disfrutar de un picnic en el campo con productos locales. Situado en el coraz\u00f3n de la campi\u00f1a mallorquina, a los pies de la Serra de Tramuntana, Es Cab\u00e0s ofrece un entorno de ensue\u00f1o para acoger retiros hol\u00edsticos (de yoga). Los espacios interiores y exteriores son perfectos para celebrar clases y talleres.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<div class=\"bellvueblock \"><img decoding=\"async\" src=\"https:\/\/www.privatepropertymallorca.com\/wp-content\/uploads\/2020\/02\/best_icon-159x300.png\" alt=\"bellvue\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La Finca Es Cab\u00e0s ha sido habitada y cultivada desde hace miles de a\u00f1os, con todos los pueblos que nos precedieron dejando su huella en la tierra. Esta antigua finca de origen talai\u00f3tico y morisco, bellamente restaurada, se encuentra a los pies de la Serra de Tramuntana a tan s\u00f3lo 15 minutos de Palma. El cortijo en s\u00ed es de origen morisco y en las cumbres que rodean la finca se encuentran otros restos de la \u00e9poca romana y talai\u00f3tica.<\/p>\n","protected":false},"author":4,"featured_media":422094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[1074,1073],"tags":[],"class_list":{"0":"post-422081","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-perfect-hideaways-mallorca","8":"category-revista"},"_links":{"self":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/posts\/422081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/comments?post=422081"}],"version-history":[{"count":0,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/posts\/422081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/media\/422094"}],"wp:attachment":[{"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/media?parent=422081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/categories?post=422081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.privatepropertymallorca.com\/es\/wp-json\/wp\/v2\/tags?post=422081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}